{"id":9893,"date":"2024-07-31T10:54:25","date_gmt":"2024-07-31T13:54:25","guid":{"rendered":"https:\/\/sabuguinho.com.br\/site\/?p=9893"},"modified":"2024-07-31T10:54:25","modified_gmt":"2024-07-31T13:54:25","slug":"educacao-eja-esta-com-matriculas-abertas-para-segundo-semestre-de-2024-2","status":"publish","type":"post","link":"https:\/\/sabuguinho.com.br\/site\/educacao-eja-esta-com-matriculas-abertas-para-segundo-semestre-de-2024-2\/","title":{"rendered":"EDUCA\u00c7\u00c3O &#8211; EJA est\u00e1 com matr\u00edculas abertas para segundo semestre de 2024"},"content":{"rendered":"<p>Modalidade de ensino \u00e9 voltada para quem n\u00e3o p\u00f4de finalizar estudos na idade adequada<\/p>\n<p>A Educa\u00e7\u00e3o de Jovens e Adultos (EJA) de Avar\u00e9 est\u00e1 com matr\u00edculas abertas para quem deseja concluir o Ensino Fundamental.<br \/>\nA modalidade \u00e9 direcionada a adultos que, por algum motivo, n\u00e3o puderam finalizar os estudos na idade certa.<br \/>\n\u201c\u00c9 uma grande chance para quem deseja concluir os estudos, ter acesso a novas oportunidades de trabalho e ampliar seus conhecimentos. Matricule-se j\u00e1. \u00c9 gratuito\u201d, destaca a Secretaria Municipal de Educa\u00e7\u00e3o.<br \/>\nMinistradas no per\u00edodo noturno, as aulas t\u00eam in\u00edcio em 29 de julho. As matr\u00edculas para o segundo semestre de 2024 est\u00e3o dispon\u00edveis nas escolas municipais Salim Antonio Curiati (1\u00ba ao 9\u00ba ano), Maria Theresa de Oliveira Picalho\/Dondoca (1\u00ba ao 9\u00ba ano) e Fausto dos Santos Rodrigues (1\u00ba ao 5\u00ba ano).<\/p>\n<p>Matr\u00edculas<\/p>\n<p>As matr\u00edculas devem ser feitas nas escolas acima mencionadas por meio dos telefones (14) 3731-7253, (14) 3733-7017 e (14) 3732-7541, respectivamente.<br \/>\nA EJA de Avar\u00e9 conta com uma parceria com o Instituto Federal de S\u00e3o Paulo (IFSP), oferecendo aos alunos ainda mais oportunidades de qualifica\u00e7\u00e3o profissional, conclui a Educa\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Modalidade de ensino \u00e9 voltada para quem n\u00e3o p\u00f4de finalizar estudos na idade adequada A Educa\u00e7\u00e3o de Jovens e Adultos (EJA) de Avar\u00e9 est\u00e1 com matr\u00edculas abertas para quem deseja concluir o Ensino Fundamental. A modalidade \u00e9 direcionada a adultos que, por algum motivo, n\u00e3o puderam finalizar os estudos na idade certa. \u201c\u00c9 uma grande [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":9894,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-9893","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-locais"],"_links":{"self":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/9893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/comments?post=9893"}],"version-history":[{"count":1,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/9893\/revisions"}],"predecessor-version":[{"id":9895,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/9893\/revisions\/9895"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media\/9894"}],"wp:attachment":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media?parent=9893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/categories?post=9893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/tags?post=9893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}