{"id":912,"date":"2023-11-23T04:25:07","date_gmt":"2023-11-23T07:25:07","guid":{"rendered":"https:\/\/sabuguinho.com.br\/site\/?p=912"},"modified":"2023-11-23T04:25:07","modified_gmt":"2023-11-23T07:25:07","slug":"cano-decide-e-fluminense-supera-sao-paulo-no-maracana","status":"publish","type":"post","link":"https:\/\/sabuguinho.com.br\/site\/cano-decide-e-fluminense-supera-sao-paulo-no-maracana\/","title":{"rendered":"Cano decide e Fluminense supera S\u00e3o Paulo no Maracan\u00e3"},"content":{"rendered":"<p>Cruzeiro e Vasco ficam no 2 a 2 pelo Brasileiro<\/p>\n<p>Contando com o faro de gol do argentino Germ\u00e1n Cano, o Fluminense derrotou o S\u00e3o Paulo por 1 a 0, na noite desta quarta-feira (22) no est\u00e1dio do Maracan\u00e3, em partida atrasada da 32\u00aa rodada do Campeonato Brasileiro que foi transmitida pela R\u00e1dio Nacional.<br \/>\nO jogo tinha um car\u00e1ter especial, pois envolvia os atuais campe\u00f5es da Copa Libertadores e da Copa do Brasil (inclusive, antes de a bola rolar, os jogadores das duas equipes trocaram faixas de campe\u00f5es). Por\u00e9m, todo o esp\u00edrito festivo ficou para tr\u00e1s ap\u00f3s o apito inicial.<br \/>\nDesde o primeiro minuto o que se viu foram jogadas duras e muitas faltas de lado a lado. Inclusive, o S\u00e3o Paulo acabou ficando com um jogador a menos logo aos 27 minutos do primeiro tempo, quando o volante Gabriel Neves pisou no p\u00e9 de Thiago Santos. Com um homem a mais o Fluminense tomou conta da partida e conseguiu garantir a vit\u00f3ria aos 8 minutos da etapa final em jogada de contra-ataque que culminou em chute da entrada da \u00e1rea de Cano.<br \/>\nCom a vit\u00f3ria a equipe das Laranjeiras chegou \u00e0 8\u00aa posi\u00e7\u00e3o com 50 pontos. J\u00e1 o S\u00e3o Paulo permaneceu com 46 pontos, agora na 10\u00aa posi\u00e7\u00e3o.<\/p>\n<p>Empate no Mineir\u00e3o<br \/>\nEm outra partida atrasada, mas da 33\u00aa rodada, Cruzeiro e Vasco ficaram no 2 a 2 no est\u00e1dio do Mineir\u00e3o. O Cruzmaltino abriu o placar com Puma Rodr\u00edguez, a Raposa alcan\u00e7ou a virada com gols de Bruno Rodrigues e de Arthur Gomes, mas Gabriel Pec garantiu o empate final.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/sabuguinho.com.br\/site\/wp-content\/uploads\/2023\/11\/F_k7v9WW8AAjJBQ-120x150.jpeg\" alt=\"\" width=\"120\" height=\"150\" class=\"alignnone size-medium wp-image-913\" srcset=\"https:\/\/sabuguinho.com.br\/site\/wp-content\/uploads\/2023\/11\/F_k7v9WW8AAjJBQ-120x150.jpeg 120w, https:\/\/sabuguinho.com.br\/site\/wp-content\/uploads\/2023\/11\/F_k7v9WW8AAjJBQ-410x512.jpeg 410w, https:\/\/sabuguinho.com.br\/site\/wp-content\/uploads\/2023\/11\/F_k7v9WW8AAjJBQ.jpeg 720w\" sizes=\"auto, (max-width: 120px) 100vw, 120px\" \/><\/p>\n<p>Com o resultado tanto Vasco como Cruzeiro chegam aos 41 pontos, ainda permanecendo muito pr\u00f3ximos da zona do rebaixamento do Brasileiro.<\/p>\n<p>Edi\u00e7\u00e3o: F\u00e1bio Lisboa<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cruzeiro e Vasco ficam no 2 a 2 pelo Brasileiro Contando com o faro de gol do argentino Germ\u00e1n Cano, o Fluminense derrotou o S\u00e3o Paulo por 1 a 0, na noite desta quarta-feira (22) no est\u00e1dio do Maracan\u00e3, em partida atrasada da 32\u00aa rodada do Campeonato Brasileiro que foi transmitida pela R\u00e1dio Nacional. O [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":914,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"class_list":["post-912","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-esportes"],"_links":{"self":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/comments?post=912"}],"version-history":[{"count":1,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/912\/revisions"}],"predecessor-version":[{"id":915,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/912\/revisions\/915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media\/914"}],"wp:attachment":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media?parent=912"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/categories?post=912"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/tags?post=912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}