{"id":815,"date":"2023-11-18T11:42:33","date_gmt":"2023-11-18T14:42:33","guid":{"rendered":"https:\/\/sabuguinho.com.br\/site\/?p=815"},"modified":"2023-11-18T11:42:33","modified_gmt":"2023-11-18T14:42:33","slug":"mega-sena-sorteia-neste-sabado-premio-acumulado-em-r-43-milhoes","status":"publish","type":"post","link":"https:\/\/sabuguinho.com.br\/site\/mega-sena-sorteia-neste-sabado-premio-acumulado-em-r-43-milhoes\/","title":{"rendered":"Mega-Sena sorteia neste s\u00e1bado pr\u00eamio acumulado em R$ 43 milh\u00f5es"},"content":{"rendered":"<p>As apostas podem ser feitas at\u00e9 as 19h, hor\u00e1rio de Bras\u00edlia<\/p>\n<p>As seis dezenas do concurso 2.657 da Mega-Sena ser\u00e3o sorteadas, a partir das 20h (hor\u00e1rio de Bras\u00edlia), no Espa\u00e7o da Sorte, localizado na Avenida Paulista, n\u00ba 750, na cidade de S\u00e3o Paulo, com transmiss\u00e3o ao vivo pelo canal da Caixa no YouTube e no Facebook das Loterias Caixa.<br \/>\nCaso apenas um ganhador ganhe o pr\u00eamio da faixa principal e aplique todo o valor na poupan\u00e7a, receber\u00e1 R$ 261 mil de rendimento no primeiro m\u00eas. O pr\u00eamio est\u00e1 acumulado em R$ 43 milh\u00f5es.<br \/>\nAs apostas podem ser feitas at\u00e9 as 19h (hor\u00e1rio de Bras\u00edlia) nas casas lot\u00e9ricas credenciadas pela Caixa, em todo o pa\u00eds ou pela internet. O jogo simples, com seis n\u00fameros marcados, custa R$ 5.<\/p>\n<p>Mega da Virada<\/p>\n<p>As apostas para a Mega da Virada j\u00e1 podem ser feitas com o volante espec\u00edfico em qualquer lot\u00e9rica do pa\u00eds ou nos canais digitais das Loterias Caixa. O pr\u00eamio estimado nesta edi\u00e7\u00e3o \u00e9 de R$ 550 milh\u00f5es, o maior da hist\u00f3ria das loterias da caixa. O sorteio ser\u00e1 realizado no dia 31 de dezembro.<br \/>\nO pr\u00eamio da Mega da Virada n\u00e3o acumula, ou seja, se n\u00e3o houver ganhadores na faixa principal, com acerto de 6 n\u00fameros, o pr\u00eamio ser\u00e1 dividido entre os acertadores da 2\u00aa faixa (com o acerto de 5 n\u00fameros) e assim por diante.<br \/>\nCaso apenas um ganhador leve o pr\u00eamio e aplique todo o valor na poupan\u00e7a, receber\u00e1 R$ 3,3 milh\u00f5es no primeiro m\u00eas.<\/p>\n<p>Edi\u00e7\u00e3o: A\u00e9cio Amado<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As apostas podem ser feitas at\u00e9 as 19h, hor\u00e1rio de Bras\u00edlia As seis dezenas do concurso 2.657 da Mega-Sena ser\u00e3o sorteadas, a partir das 20h (hor\u00e1rio de Bras\u00edlia), no Espa\u00e7o da Sorte, localizado na Avenida Paulista, n\u00ba 750, na cidade de S\u00e3o Paulo, com transmiss\u00e3o ao vivo pelo canal da Caixa no YouTube e no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":363,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-815","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/comments?post=815"}],"version-history":[{"count":1,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/815\/revisions"}],"predecessor-version":[{"id":816,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/815\/revisions\/816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media\/363"}],"wp:attachment":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media?parent=815"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/categories?post=815"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/tags?post=815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}