{"id":722,"date":"2023-11-15T11:00:56","date_gmt":"2023-11-15T14:00:56","guid":{"rendered":"https:\/\/sabuguinho.com.br\/site\/?p=722"},"modified":"2023-11-15T11:00:56","modified_gmt":"2023-11-15T14:00:56","slug":"musica-milton-nascimento-e-a-dupla-chitaozinho-e-xororo-fazem-encontro-historico-na-tv","status":"publish","type":"post","link":"https:\/\/sabuguinho.com.br\/site\/musica-milton-nascimento-e-a-dupla-chitaozinho-e-xororo-fazem-encontro-historico-na-tv\/","title":{"rendered":"M\u00daSICA  &#8211; Milton Nascimento e a dupla Chit\u00e3ozinho e Xoror\u00f3 fazem encontro hist\u00f3rico na TV"},"content":{"rendered":"<p>Artistas participam do &#8216;Som Brasil&#8217;, na Globo, e falam sobre o projeto que lan\u00e7am juntos<\/p>\n<p>O TEMPO ENTRETENIMENto<\/p>\n<p>Globo<\/p>\n<p>O \u2018Som Brasil\u2019 desta quarta-feira (15) vai promover um encontro hist\u00f3rico entre a dupla Chit\u00e3ozinho &#038; Xoror\u00f3 e Milton Nascimento. Ser\u00e1 a primeira vez que eles cantam juntos e falam sobre o projeto que desenvolveram ainda durante a pandemia e que ser\u00e1 lan\u00e7ado agora: o EP \u201cOutros Cantos\u201d. O programa, apresentado por Pedro Bial, vai ao ar ap\u00f3s a novela \u201cTodas as Flores\u201d.<br \/>\n\u201cOutros Cantos\u201d foi gravado de maneira remota, com cada artista em sua casa. O \u201cSom Brasil\u201d marca o primeiro encontro deles para falar e apresentar o projeto, que traz Milton cantando sertanejo. Ao todo, o EP conta com sete faixas. A dupla Chit\u00e3ozinho e Xoror\u00f3 canta sucessos de Milton e vice-versa. O ex-integrante do Clube da Esquina, inclusive, interpreta um cl\u00e1ssico da m\u00fasica sertaneja, \u201cEvid\u00eancias\u201d, lan\u00e7ada pelos irm\u00e3os.<br \/>\n\u201cQuando ouvi \u2018Evid\u00eancias\u2019 na voz do Milton o meu queixo caiu, acho que a roupagem da m\u00fasica caiu perfeitamente para a voz dele\u201d, comemora Xoror\u00f3.  As vers\u00f5es s\u00e3o apresentadas com exclusividade no \u2018Som Brasil\u2019 antes de estarem dispon\u00edveis nas plataformas de \u00e1udio. Outras can\u00e7\u00f5es presentes em \u201cOutros Cantos\u201d, apresentadas no programa, s\u00e3o \u201cBailes da Vida\u201d e \u201cSeu Bento e Dona Linda&#8221;.<br \/>\nProduzido pela mesma equipe do programa \u201cConversa com Bial\u201d, o \u201cSom Brasil\u201d contempla os musicais in\u00e9ditos e uma entrevista conduzida por Pedro Bial. Junto com Augusto Nascimento, filho de Milton, eles compartilham hist\u00f3rias nunca contadas, tanto pessoais quanto das carreiras, que passeia por diversos momentos em que os tr\u00eas dividiram os palcos ou a tela da TV. Exploram tamb\u00e9m as influ\u00eancias musicais que um exerce sobre o outro, o surgimento da ideia de \u201cEncantos\u201d, e o convite a Milton.<\/p>\n<p>Legenda<br \/>\nMilton Nascimento e a dupla Chit\u00e3ozinho &#038; Xoror\u00f3 na grava\u00e7\u00e3o do programa &#8216;Som Brasil&#8217; | Foto: F\u00e1bio Rocha \/ Globo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artistas participam do &#8216;Som Brasil&#8217;, na Globo, e falam sobre o projeto que lan\u00e7am juntos O TEMPO ENTRETENIMENto Globo O \u2018Som Brasil\u2019 desta quarta-feira (15) vai promover um encontro hist\u00f3rico entre a dupla Chit\u00e3ozinho &#038; Xoror\u00f3 e Milton Nascimento. Ser\u00e1 a primeira vez que eles cantam juntos e falam sobre o projeto que desenvolveram ainda [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56],"tags":[],"class_list":["post-722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-social"],"_links":{"self":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/comments?post=722"}],"version-history":[{"count":1,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/722\/revisions"}],"predecessor-version":[{"id":724,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/722\/revisions\/724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media\/723"}],"wp:attachment":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media?parent=722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/categories?post=722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/tags?post=722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}