{"id":47400,"date":"2026-07-15T13:21:08","date_gmt":"2026-07-15T16:21:08","guid":{"rendered":"https:\/\/sabuguinho.com.br\/site\/?p=47400"},"modified":"2026-07-15T13:21:08","modified_gmt":"2026-07-15T16:21:08","slug":"cultura-projeto-cinepsi-tera-exibicao-gratuita-da-animacao-encanto","status":"publish","type":"post","link":"https:\/\/sabuguinho.com.br\/site\/cultura-projeto-cinepsi-tera-exibicao-gratuita-da-animacao-encanto\/","title":{"rendered":"CULTURA* *Projeto CINEPSI   ter\u00e1 exibi\u00e7\u00e3o gratuita da *anima\u00e7\u00e3o \u201cEncanto\u201d"},"content":{"rendered":"<p>Evento acontece no dia 22 de julho no Centro Cultural Esther Pires Novaes_<\/p>\n<p>O Centro Cultural Esther Pires Novaes ser\u00e1 palco de uma noite de muita sensibilidade, reflex\u00e3o e solidariedade. O projeto CINEPSI (Psicologia, Cinema e Reflex\u00e3o), que une a s\u00e9tima arte \u00e0 an\u00e1lise psicol\u00f3gica, traz como destaque do m\u00eas de julho a exibi\u00e7\u00e3o do aclamado filme da Disney, Encanto.<br \/>\n\u200bAp\u00f3s a proje\u00e7\u00e3o, o p\u00fablico poder\u00e1 participar de uma roda de debate focada nas complexas rela\u00e7\u00f5es familiares e individuais retratadas na obra.<br \/>\n\u200b<br \/>\n*Reflex\u00e3o e Sa\u00fade Mental*<\/p>\n<p>\u200bA din\u00e2mica da fam\u00edlia Madrigal servir\u00e1 como ponto de partida para discutir os dilemas da vida moderna. O debate ser\u00e1 mediado pelo psic\u00f3logo Helton Moraes e abordar\u00e1 t\u00f3picos essenciais para o bem-estar emocional: sobrecarga, autocobran\u00e7a, expectativas, pertencimento, identidade e valor pessoal.<br \/>\n\u200b\u200bO evento \u00e9 totalmente aberto ao p\u00fablico em geral e os participantes que comparecerem \u00e0 roda de conversa receber\u00e3o um certificado de 4 horas.<br \/>\nA exibi\u00e7\u00e3o acontece no dia 22 de julho, a partir das 19h. O Centro Cultural fica na Rua Cear\u00e1, 1507. A entrada \u00e9 a doa\u00e7\u00e3o de um agasalho em bom estado.<br \/>\n\u200bO CINEPSI conta com a parceria da Prefeitura da Est\u00e2ncia Tur\u00edstica de Avar\u00e9, por meio da Secretaria Municipal da Cultura, e do psic\u00f3logo Helton Moraes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evento acontece no dia 22 de julho no Centro Cultural Esther Pires Novaes_ O Centro Cultural Esther Pires Novaes ser\u00e1 palco de uma noite de muita sensibilidade, reflex\u00e3o e solidariedade. O projeto CINEPSI (Psicologia, Cinema e Reflex\u00e3o), que une a s\u00e9tima arte \u00e0 an\u00e1lise psicol\u00f3gica, traz como destaque do m\u00eas de julho a exibi\u00e7\u00e3o do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":47401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66],"tags":[],"class_list":["post-47400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-social-sociai"],"_links":{"self":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/47400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/comments?post=47400"}],"version-history":[{"count":1,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/47400\/revisions"}],"predecessor-version":[{"id":47402,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/47400\/revisions\/47402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media\/47401"}],"wp:attachment":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media?parent=47400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/categories?post=47400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/tags?post=47400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}