{"id":24676,"date":"2025-06-10T12:40:13","date_gmt":"2025-06-10T15:40:13","guid":{"rendered":"https:\/\/sabuguinho.com.br\/site\/?p=24676"},"modified":"2025-06-10T12:40:13","modified_gmt":"2025-06-10T15:40:13","slug":"emprego-posto-de-atendimento-ao-trabalhador-divulga-vagas-de-emprego-15","status":"publish","type":"post","link":"https:\/\/sabuguinho.com.br\/site\/emprego-posto-de-atendimento-ao-trabalhador-divulga-vagas-de-emprego-15\/","title":{"rendered":"EMPREGO  Posto de Atendimento ao Trabalhador divulga vagas de emprego"},"content":{"rendered":"<p>Ofertas est\u00e3o sujeitas \u00e0 altera\u00e7\u00e3o sem qualquer aviso pr\u00e9vio<\/p>\n<p>O Posto de Atendimento ao Trabalhador (PAT) divulga a lista atualizada de vagas de emprego dispon\u00edveis em Avar\u00e9.<br \/>\nO PAT \u00e9 uma iniciativa da Secretaria do Desenvolvimento Econ\u00f4mico de S\u00e3o Paulo em parceria com a Prefeitura da Est\u00e2ncia Tur\u00edstica de Avar\u00e9, por meio da Secretaria Municipal de Ind\u00fastria e Com\u00e9rcio.<br \/>\nAs vagas s\u00e3o as seguintes: ajudante de padeiro (03), atendente de sac (01), auxiliar de limpeza (02), auxiliar de cozinha (02), almoxarife (02), analista de contabilidade (01), analista de marketing (01), analista de log\u00edstica (01), armador de ferragem (01), assistente de vendas (01), atendente de lanchonete (01), auxiliar de manuten\u00e7\u00e3o (predial) (03), cuidadora de crian\u00e7as (bab\u00e1) (01), balconista (01), caseiro (01), campeiro (01), consultor de vendas (01), comprador (01), empregada dom\u00e9stica (01), encanador (01), fiscal de opera\u00e7\u00e3o (01), operador de corte\/plasma (01), mec\u00e2nico de autos (02), montador (02), montador de m\u00f3veis planejados (03), mec\u00e2nico de m\u00e1quinas (01), motorista escolar (04), oficial de manuten\u00e7\u00e3o (01), repositor de pe\u00e7as (03), pintor (estrutura met\u00e1lica) (01), pedreiro (03), soldador mec\u00e2nico (01), vendedor interno (01).<\/p>\n<p>Sujeitas \u00e0 altera\u00e7\u00e3o<\/p>\n<p>As vagas est\u00e3o sujeitas \u00e0 altera\u00e7\u00e3o sem aviso pr\u00e9vio conforme o preenchimento ou retirada das mesmas pelas empresas.<\/p>\n<p>Empregador<\/p>\n<p>\u00c9 necess\u00e1rio o cadastro da empresa ou pessoa f\u00edsica no endere\u00e7o eletr\u00f4nico empregabrasil.mte.gov.br ou diretamente no PAT para a disponibiliza\u00e7\u00e3o de vagas e processo seletivo.<\/p>\n<p>Candidatos<\/p>\n<p>J\u00e1 o candidato deve se cadastrar no site empregabrasil.mte.gov.br ou por meio do PAT. Os documentos necess\u00e1rios s\u00e3o o PIS, NIT, PASEP, Bolsa fam\u00edlia, Cart\u00e3o Cidad\u00e3o, Carteira de Trabalho, RG, CPF e CNH.<br \/>\n\u00c9 importante ainda que o candidato mantenha seu cadastro atualizado junto ao PAT, o que pode ser decisivo no processo de contrata\u00e7\u00e3o.<\/p>\n<p>Servi\u00e7o<\/p>\n<p>O PAT fica na Casa do Cidad\u00e3o (Rua Bahia, n\u00ba 1.580, centro). Outras informa\u00e7\u00f5es pelo telefone (14) 3732-1414.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ofertas est\u00e3o sujeitas \u00e0 altera\u00e7\u00e3o sem qualquer aviso pr\u00e9vio O Posto de Atendimento ao Trabalhador (PAT) divulga a lista atualizada de vagas de emprego dispon\u00edveis em Avar\u00e9. O PAT \u00e9 uma iniciativa da Secretaria do Desenvolvimento Econ\u00f4mico de S\u00e3o Paulo em parceria com a Prefeitura da Est\u00e2ncia Tur\u00edstica de Avar\u00e9, por meio da Secretaria Municipal [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":24677,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24676","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politicas-em-geral"],"_links":{"self":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/24676","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/comments?post=24676"}],"version-history":[{"count":1,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/24676\/revisions"}],"predecessor-version":[{"id":24678,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/24676\/revisions\/24678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media\/24677"}],"wp:attachment":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media?parent=24676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/categories?post=24676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/tags?post=24676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}