{"id":10118,"date":"2024-08-05T13:43:06","date_gmt":"2024-08-05T16:43:06","guid":{"rendered":"https:\/\/sabuguinho.com.br\/site\/?p=10118"},"modified":"2024-08-05T13:43:06","modified_gmt":"2024-08-05T16:43:06","slug":"faculdade-eduvale-e-unesp-bauru-firmam-convenio-de-projeto-de-pesquisa","status":"publish","type":"post","link":"https:\/\/sabuguinho.com.br\/site\/faculdade-eduvale-e-unesp-bauru-firmam-convenio-de-projeto-de-pesquisa\/","title":{"rendered":"FACULDADE EDUVALE E UNESP BAURU FIRMAM CONV\u00caNIO DE PROJETO DE PESQUISA"},"content":{"rendered":"<p>A Faculdade Eduvale de Avar\u00e9 e Faculdade de Ci\u00eancias do c\u00e2mpus de Bauru da Universidade Estadual Paulista \u201cJ\u00falio de Mesquita Filho\u201d (UNESP) firmaram um conv\u00eanio de projeto de pesquisa formalizado na publica\u00e7\u00e3o de 04 de julho deste ano no Di\u00e1rio Oficial da Uni\u00e3o.<br \/>\nA conjuga\u00e7\u00e3o de esfor\u00e7os consiste na coopera\u00e7\u00e3o t\u00e9cnica, cient\u00edfica e acad\u00eamica com o objetivo de desenvolver o projeto &#8220;A\u00e7\u00f5es colaborativas na Constru\u00e7\u00e3o de uma Sociedade Equitativa: Direitos humanos, Sa\u00fade, Inclus\u00e3o e diversidade como Pilares&#8221;.<br \/>\nCoordenada por Vera Lucia Messias Fialho Capellini (professora e diretora da Faculdade de Ci\u00eancias da UNESP\/Bauru) com a Dra. Ver\u00f4nica Lima dos Reis (coordenadora e professora do curso de Psicologia da Faculdade Eduvale), a parceria ter\u00e1 dura\u00e7\u00e3o de tr\u00eas anos. Os pesquisadores e docentes Eliana Marques Zanata, Fabiana Cordeiro, Amanda Dipp\u00f3lito, Vin\u00edcius Iuri de Menezes, Claudineia Fernandes, Ariane Silva, Mar\u00edlia dos Santos, Ligia Corazza e Samira Tonin formam a equipe de apoio complementar.<br \/>\nDireitos humanos, sa\u00fade, inclus\u00e3o e diversidade que s\u00e3o metas dos Objetivos do Desenvolvimento Sustent\u00e1vel da Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas (ONU) s\u00e3o o foco do trabalho que tem como intuito contribuir com a promo\u00e7\u00e3o da sa\u00fade e bem-estar de estudantes, fam\u00edlias e educadores nas comunidades escolares de Avar\u00e9\/SP.<br \/>\nDesenvolvimento de habilidades socioemocionais, igualdade de g\u00eanero, forma\u00e7\u00e3o de professores, pr\u00e1ticas, avalia\u00e7\u00f5es inclusivas e educa\u00e7\u00e3o especial ser\u00e3o alguns dos t\u00f3picos das a\u00e7\u00f5es realizadas.<br \/>\nA colabora\u00e7\u00e3o tamb\u00e9m promover\u00e1 a orienta\u00e7\u00e3o compartilhada de estudantes, a produ\u00e7\u00e3o de livros e artigos cient\u00edficos, a apresenta\u00e7\u00e3o de eventos acad\u00eamicos-cient\u00edficos e o interc\u00e2mbio de docentes e est\u00e1gios.<br \/>\n\u201c\u00c9 uma grande honra e uma conquista para a Eduvale! \u00c9 momento de vibrar com a nossa comunidade acad\u00eamica com esta parceria de t\u00e3o grande valia que incentiva a educa\u00e7\u00e3o, a inclus\u00e3o e o social\u201d, ressaltou o Dr. Claudio Mansur Salom\u00e3o, presidente mantenedor da Faculdade Eduvale.<\/p>\n<p>legenda: Objetivo \u00e9 desenvolver o projeto &#8220;A\u00e7\u00f5es colaborativas na Constru\u00e7\u00e3o de uma Sociedade Equitativa<\/p>\n<p>FONTE DA FOTO: INTERNET ILUSTRATIVA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Faculdade Eduvale de Avar\u00e9 e Faculdade de Ci\u00eancias do c\u00e2mpus de Bauru da Universidade Estadual Paulista \u201cJ\u00falio de Mesquita Filho\u201d (UNESP) firmaram um conv\u00eanio de projeto de pesquisa formalizado na publica\u00e7\u00e3o de 04 de julho deste ano no Di\u00e1rio Oficial da Uni\u00e3o. A conjuga\u00e7\u00e3o de esfor\u00e7os consiste na coopera\u00e7\u00e3o t\u00e9cnica, cient\u00edfica e acad\u00eamica com [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10119,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[58],"tags":[],"class_list":["post-10118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-locais"],"_links":{"self":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/10118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/comments?post=10118"}],"version-history":[{"count":1,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/10118\/revisions"}],"predecessor-version":[{"id":10120,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/10118\/revisions\/10120"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media\/10119"}],"wp:attachment":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media?parent=10118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/categories?post=10118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/tags?post=10118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}