{"id":10106,"date":"2024-08-05T09:07:30","date_gmt":"2024-08-05T12:07:30","guid":{"rendered":"https:\/\/sabuguinho.com.br\/site\/?p=10106"},"modified":"2024-08-05T09:07:30","modified_gmt":"2024-08-05T12:07:30","slug":"caculinha-musico-do-domingao-do-faustao-morre-aos-86-anos","status":"publish","type":"post","link":"https:\/\/sabuguinho.com.br\/site\/caculinha-musico-do-domingao-do-faustao-morre-aos-86-anos\/","title":{"rendered":"Ca\u00e7ulinha, m\u00fasico do Doming\u00e3o do Faust\u00e3o, morre aos 86 anos"},"content":{"rendered":"<p>Artista estava internado no Hospital Sancta Maggiore, em S\u00e3o Paulo, onde se recuperava de um infarto.<\/p>\n<p>Por g1 SP \u2014 S\u00e3o Paulo<\/p>\n<p>O m\u00fasico e compositor Rubens Ant\u00f4nio da Silva, mais conhecido como Ca\u00e7ulinha, morreu aos 86 anos na madrugada desta segunda-feira (5), segundo familiares.<br \/>\nEle estava internado havia cerca de dez dias no Hospital Sancta Maggiore, em S\u00e3o Paulo, onde se recuperava de um infarto<\/p>\n<p>Ca\u00e7ulinha se tornou nacionalmente conhecido por suas participa\u00e7\u00f5es no Doming\u00e3o do Faust\u00e3o, ao produzir a trilha sonora do programa ao vivo por mais de 20 anos.<br \/>\nTamb\u00e9m comandava a banda que abria e fechava os intervalos do programa humor\u00edstico &#8216;Sai de Baixo&#8217;.<br \/>\nDe acordo com os familiares, o vel\u00f3rio ser\u00e1 na Capela do Cemit\u00e9rio S\u00e3o Paulo, em Pinheiros, na Zona Oeste da capital paulista, das 11 \u00e0s 15h. O sepultamento ser\u00e1 \u00e0s 16h no mesmo local.<\/p>\n<p>Legenda<br \/>\nCa\u00e7ulinha durante programa Sai de Baixo, da TV Globo \u2014 Foto: Acervo TV Globo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Artista estava internado no Hospital Sancta Maggiore, em S\u00e3o Paulo, onde se recuperava de um infarto. Por g1 SP \u2014 S\u00e3o Paulo O m\u00fasico e compositor Rubens Ant\u00f4nio da Silva, mais conhecido como Ca\u00e7ulinha, morreu aos 86 anos na madrugada desta segunda-feira (5), segundo familiares. Ele estava internado havia cerca de dez dias no Hospital [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":10107,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[61],"tags":[],"class_list":["post-10106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral"],"_links":{"self":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/10106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/comments?post=10106"}],"version-history":[{"count":1,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/10106\/revisions"}],"predecessor-version":[{"id":10108,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/posts\/10106\/revisions\/10108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media\/10107"}],"wp:attachment":[{"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/media?parent=10106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/categories?post=10106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sabuguinho.com.br\/site\/wp-json\/wp\/v2\/tags?post=10106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}